{"id":214,"name":"Hannes Kutza","url":"","description":"","link":"https:\/\/www.camp4.de\/blog\/author\/hannes-kutza\/","slug":"hannes-kutza","avatar_urls":{"24":"https:\/\/www.camp4.de\/blog\/wp-content\/uploads\/2024\/06\/Hannes-Kutza-242-66x66.jpg","48":"https:\/\/www.camp4.de\/blog\/wp-content\/uploads\/2024\/06\/Hannes-Kutza-242-66x66.jpg","96":"https:\/\/www.camp4.de\/blog\/wp-content\/uploads\/2024\/06\/Hannes-Kutza-242.jpg"},"meta":{"jetpack_donation_warning_dismissed":false},"_links":{"self":[{"href":"https:\/\/www.camp4.de\/blog\/wp-json\/wp\/v2\/users\/214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.camp4.de\/blog\/wp-json\/wp\/v2\/users"}]}}