{"id":6903,"date":"2013-11-18T22:18:53","date_gmt":"2013-11-18T20:18:53","guid":{"rendered":"https:\/\/www.camp4.de\/blog\/?p=6903"},"modified":"2024-07-09T16:38:09","modified_gmt":"2024-07-09T14:38:09","slug":"simpel-und-gut-der-alb-woodstove","status":"publish","type":"post","link":"https:\/\/www.camp4.de\/blog\/outdoor-szene\/allgemein\/simpel-und-gut-der-alb-woodstove\/","title":{"rendered":"Simpel und Gut: Der Alb Woodstove"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong>Hans ist Verk\u00e4ufer im CAMP4 und hat einen neuen Kocher getestet. Hans ist so begeistert, dass er den Kocher auch gleich f\u00fcr den privaten Gebrauch bestellt hat. Welcher das ist und warum Hans damit seiner Frau einen riesen Schrecken eingejagt hat, lest ihr hier:<\/strong><\/p>\n<p><!--more--><\/p>\n<p><strong>Camplog:<\/strong><a title=\"Weblog Artikel\" href=\"https:\/\/www.camp4.de\/blog\/camp4-team\/hans-jorg-scholze\/\"> Hans<\/a>, welchen Kocher hast du getestet?<\/p>\n<p><strong>Hans:<\/strong> Ich habe den <a title=\"Webshop\" href=\"https:\/\/www.camp4.de\/alb-forming\/bush-buddy-holzofen.html\" target=\"_blank\" rel=\"noopener\">Alb Wood Stove<\/a> Kocher ausprobiert.<\/p>\n<p><strong><strong>Camplog:<\/strong> <\/strong>Wie und wo warst du unterwegs?<br \/>\n<strong><br \/>\n<strong>Hans:<\/strong> <\/strong>Leider habe ich den Kocher nicht unter wirklichen Outdoorbedingungen testen k\u00f6nnen. Ich habe den Wood Stove zu Hause in unserer Garage angefeuert. Es ging mir in erster Linie auch um die Funktionsweise. Aber ich habe das Garagentor offen gelassen, so gab es immerhin einen echten Windzug.<\/p>\n<p><a href=\"https:\/\/www.camp4.de\/alb-forming\/bush-buddy-holzofen.html\">&gt; Der Alb Woodstove im CAMP4 Shop<\/a><\/p>\n<p><strong><strong>Camplog:<\/strong> <\/strong>Wie funktioniert der Kocher?<br \/>\n<strong><br \/>\n<strong>Hans:<\/strong> <\/strong>Als erstes nat\u00fcrlich auspacken und den Packsack herausnehmen. Das Brenngut einf\u00fcllen, am besten eignet sich trockenes Material wie trockenes Holz, kleine St\u00f6ckchen, Tannenzapfen oder wie ich aus dem hauseigenen Garten Weinmutskieferzapfen.<\/p>\n<p>Vorher muss der Outdoor-Koch nat\u00fcrlich den Topfaufsatz herausnehmen, diesen umdrehen und den Topf darauf stellen. Wasser rein und das Brennmaterial anz\u00fcnden. Hier darf man sich nicht wundern, dass das Brenngut stark ru\u00dft, raucht und qualmt.<\/p>\n<p>Wenn es aufh\u00f6rt zu rauchen, dann entsteht der so genannte Schloteffekt: Der doppelwandige Kocher saugt von unten Luft an und es brennt. Ganz einfach. Funktioniert total gut und ist auch noch richtig simpel. Mit einem Messer oder spitzen Gegenstand l\u00e4sst sich auch v\u00f6llig unproblematisch Brenngut nachschieben.<\/p>\n<p><strong><strong>Camplog:<\/strong> <\/strong>Wie schnell kocht das Wasser?<br \/>\n<strong><br \/>\n<strong>Hans:<\/strong> <\/strong>Ich hab die Zeit jetzt nicht genau gemessen, aber ich denke ein Liter Wasser kocht nach ungef\u00e4hr f\u00fcnf bis sechs Minuten.<\/p>\n<p><strong><strong>Camplog:<\/strong> <\/strong>F\u00fcr wen, glaubst du, eignet sich der Kocher?<br \/>\n<strong><br \/>\n<strong>Hans:<\/strong> <\/strong>F\u00fcr alle, die drau\u00dfen autark unterwegs sind und keine Kartuschen rumschleppen wollen. Mit dem Kocher hat man keinen Abfall, muss nichts mitnehmen und ist wie gesagt v\u00f6llig autark, was das Brennmaterial angeht.<\/p>\n<p><strong><strong>Camplog:<\/strong> <\/strong>Was ist, wenn man nichts Brennbares findet?<br \/>\n<strong><br \/>\n<strong>Hans:<\/strong> <\/strong>Wenn man tats\u00e4chlich Angst hat, nichts Brennbares zu finden, dann empfehle ich einen kleinen <a title=\"Webshop\" href=\"https:\/\/www.camp4.de\/spirituskocher\/\">Spiritusbrenner<\/a> mitzunehmen. Den einfach in die \u00d6ffnung f\u00fcr das Brennmaterial stellen und los geht\u2019s. So ist auch alles super windgesch\u00fctzt.<\/p>\n<p><strong><strong>Camplog:<\/strong> <\/strong>Den Kocher gibt es in zwei Varianten, was sind die Unterschiede?<br \/>\n<strong><br \/>\n<strong>Hans:<\/strong> <\/strong>Ganz einfach: Stahl oder Titan. Der Stahl Kocher wiegt 452 Gramm und ist damit deutlich schwerer als der Titan Kocher. Aber auch viel g\u00fcnstiger. Das Preis-Leistungs-Verh\u00e4ltnis ist bei der Stahl Variante unschlagbar. 39,95 Euro finde ich grandios!<\/p>\n<p>Das Ganze in Titan kostet gleich knapp das Doppelte. Und wer sich den Wood Stove\u00a0in Titan g\u00f6nnt, der sollte auch gleich das passende Kochset von Snowpeak\u00a0dazu nehmen. Da passt der Kocher zusammengebaut n\u00e4mlich genau in den Topf.<\/p>\n<p><strong><strong>Camplog:<\/strong><\/strong> Bei all dem Lob, gibt es auch etwas Negatives?<br \/>\n<strong><br \/>\n<strong>Hans:<\/strong> <\/strong>Auf Zeltpl\u00e4tzen mit strengen Reglementierungen w\u00fcrde ich von dem Wood Stove\u00a0abraten, denn er qualmt schon sehr stark. Das offene Feuer macht sicher nicht nur meine Frau nerv\u00f6s (Anm. d. Red. Hans\u2018 Frau hat einen riesen Schreck bekommen und dachte, die Garage brennt ab). Dadurch dass man quasi auf einem offenen Feuer kocht, ist der Woodstove nat\u00fcrlich absolut ungeeignet f\u00fcr Kinder. Auch werden die T\u00f6pfe sehr hei\u00df und ru\u00dfig. Ohne Topf-Halterung geht\u2019s gar nicht.<\/p>\n<p><strong><strong>Camplog:<\/strong> <\/strong>Wohin wirst du den Kocher als erstes mitnehmen?<\/p>\n<p><strong>Hans:<\/strong> Das wei\u00df ich noch nicht. Aber wof\u00fcr ich ihn das erste mal verwenden m\u00f6chte, das wei\u00df ich schon: Ich finde den Wood Stove\u00a0super f\u00fcr weihnachtlichen Gl\u00fchwein im Garten. Das Feuer macht die richtige Stimmung und ist sch\u00f6n warm. Oder zum Wintergrillen macht er sicher auch viel Spa\u00df.<\/p>\n<p>Hans, viel Spa\u00df beim Gl\u00fchwein im Garten und ich freue mich auf ein paar sch\u00f6ne Worte von diesem Winterspektakel!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Hans ist Verk\u00e4ufer im CAMP4 und hat einen neuen Kocher getestet. Hans ist so begeistert, dass er den Kocher [&hellip;]<\/p>\n","protected":false},"author":146,"featured_media":6904,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1,6,587],"tags":[918,467,919,212],"class_list":["post-6903","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-produkte","category-testbericht","tag-brennmaterial","tag-camping","tag-garage","tag-kocher"],"geo":null,"jetpack_featured_media_url":"https:\/\/www.camp4.de\/blog\/wp-content\/uploads\/2013\/11\/PB140643.gif","jetpack_shortlink":"https:\/\/wp.me\/p4csa8-1Nl","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.camp4.de\/blog\/wp-json\/wp\/v2\/posts\/6903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.camp4.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.camp4.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.camp4.de\/blog\/wp-json\/wp\/v2\/users\/146"}],"replies":[{"embeddable":true,"href":"https:\/\/www.camp4.de\/blog\/wp-json\/wp\/v2\/comments?post=6903"}],"version-history":[{"count":23,"href":"https:\/\/www.camp4.de\/blog\/wp-json\/wp\/v2\/posts\/6903\/revisions"}],"predecessor-version":[{"id":30887,"href":"https:\/\/www.camp4.de\/blog\/wp-json\/wp\/v2\/posts\/6903\/revisions\/30887"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.camp4.de\/blog\/wp-json\/wp\/v2\/media\/6904"}],"wp:attachment":[{"href":"https:\/\/www.camp4.de\/blog\/wp-json\/wp\/v2\/media?parent=6903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.camp4.de\/blog\/wp-json\/wp\/v2\/categories?post=6903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.camp4.de\/blog\/wp-json\/wp\/v2\/tags?post=6903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}